{"id":7358,"date":"2024-10-29T01:22:08","date_gmt":"2024-10-29T01:22:08","guid":{"rendered":"https:\/\/infozamoraec.com\/?p=7358"},"modified":"2024-10-29T01:22:08","modified_gmt":"2024-10-29T01:22:08","slug":"mujeres-de-la-ruralidad-compartieron-experiencias","status":"publish","type":"post","link":"https:\/\/infozamoraec.com\/index.php\/2024\/10\/29\/mujeres-de-la-ruralidad-compartieron-experiencias\/","title":{"rendered":"Mujeres de la ruralidad compartieron experiencias\u00a0"},"content":{"rendered":"<p style=\"font-weight: 400;\">Por segundo a\u00f1o consecutivo, la Prefectura de Zamora Chinchipe desarroll\u00f3 el Encuentro de Mujeres Rurales\u00a0<strong>\u201cSembrando Vida\u201d.\u00a0<\/strong>Cuyo objetivo se centr\u00f3 en seguir<strong>\u00a0f<\/strong>ortaleciendo la capacidad de liderazgo y el empoderamiento de las mujeres rurales, a trav\u00e9s del intercambio de conocimientos, habilidades y vivencias. La prefecta Karla Re\u00e1tegui lider\u00f3 este evento y mencion\u00f3 que, es deber reconocer y valorar el papel fundamental de la mujer en el desarrollo rural y la agricultura.<\/p>\n<p style=\"font-weight: 400;\">M\u00e1s de 100 mujeres entre lideresas, autoridades y emprendedoras rurales de los nueve cantones de la Provincia, acompa\u00f1aron a este encuentro marcado de ponencias sobre pol\u00edtica p\u00fablica provincial de g\u00e9nero y liderazgo; creaci\u00f3n de emprendimientos de mujeres rurales; historias de la vida de mujeres en la sociedad; mesas de trabajo con tem\u00e1ticas de emprendimientos sostenibles libres de deforestaci\u00f3n (\u2026), en coordinaci\u00f3n del CONAGOPARE de Zamora Chinchipe, Naturaleza y Cultura Internacional NCI.<\/p>\n<p style=\"font-weight: 400;\">La prefecta Karla dijo que, estos espacios con las mujeres rurales son para compartir lo bonito que est\u00e1n haciendo desde cada uno de sus espacios, este evento permite seguir tomando fuerzas y decisiones para continuar trabajando y que el pr\u00f3ximo a\u00f1o se multipliquen los logros alcanzados. Entre otros temas, mencion\u00f3 que los l\u00edmites no existen.\u00a0<strong>\u201cTenemos que revestirnos de mucha fortaleza, que todas estas acciones sirvan para que la provincia se siga fortaleciendo con nuestros emprendimientos, que dejemos un territorio en buenas condiciones para nuestras generaciones\u2026\u201d,\u00a0<\/strong>concluy\u00f3 Re\u00e1tegui.<\/p>\n<p style=\"font-weight: 400;\">Teresa Alba, presidenta de CONAGOPARE de Zamora Chinchipe, resalt\u00f3 que este acto es importante porque\u00a0<strong>\u201cd\u00eda a d\u00eda caminamos por este trayecto muchas de las veces llenos de obst\u00e1culos y que m\u00e1s bien estos espacios son escenarios para apoyarnos y demostrar que siempre se puede salir en la sociedad\u201d.<\/strong><\/p>\n<p style=\"font-weight: 400;\">Una de las ponentes, Pamela Quishpe, de la Prefectura de Pichincha, cont\u00f3 la experiencia de su instituci\u00f3n en el fortalecimiento de la participaci\u00f3n pol\u00edtica, pues, de las 23 prefecturas, 7 son mujeres, de 223 municipios, existen 42 alcaldesas y de 820 GADs Parroquiales, son 182 mujeres presidentas.\u00a0\u00a0<strong>\u201cComo Prefectura estamos apoyando con pol\u00edticas p\u00fablicas en todas las provincias, las mujeres somos m\u00e1s del 50% de poblaci\u00f3n y eso nos fortalece\u201d.<\/strong><\/p>\n<p style=\"font-weight: 400;\"><strong>\u00a0<\/strong>Para Loira \u00c1lvarez, participante, las mujeres se han convertido en el pilar fundamental de la sociedad. En este sentido, felicit\u00f3 a la Prefecta por ser la pionera principal en beneficio del sector m\u00e1s importante de la Provincia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por segundo a\u00f1o consecutivo, la Prefectura de Zamora Chinchipe desarroll\u00f3 el Encuentro de Mujeres Rurales\u00a0\u201cSembrando Vida\u201d.\u00a0Cuyo objetivo se centr\u00f3 en seguir\u00a0fortaleciendo la capacidad de liderazgo y el empoderamiento de las mujeres rurales, a trav\u00e9s del intercambio de conocimientos, habilidades y vivencias. La prefecta Karla Re\u00e1tegui lider\u00f3 este evento y mencion\u00f3 que, es deber reconocer y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/7358"}],"collection":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/comments?post=7358"}],"version-history":[{"count":2,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/7358\/revisions"}],"predecessor-version":[{"id":7361,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/7358\/revisions\/7361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media\/7359"}],"wp:attachment":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media?parent=7358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/categories?post=7358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/tags?post=7358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}