{"id":23422,"date":"2026-07-15T21:26:58","date_gmt":"2026-07-15T21:26:58","guid":{"rendered":"https:\/\/infozamoraec.com\/?p=23422"},"modified":"2026-07-15T22:11:22","modified_gmt":"2026-07-15T22:11:22","slug":"por-unanimidad-el-cne-niega-entrega-de-formularios-para-la-revocatoria-de-noboa","status":"publish","type":"post","link":"https:\/\/infozamoraec.com\/index.php\/2026\/07\/15\/por-unanimidad-el-cne-niega-entrega-de-formularios-para-la-revocatoria-de-noboa\/","title":{"rendered":"Por unanimidad el CNE niega entrega de formularios para la revocatoria de Noboa"},"content":{"rendered":"<p>Todos los integrantes del Consejo Nacional Electoral (CNE) resolvierron con cinco votos negativos no dar paso a la entrega de formularios que el frente Revocatoria.ec exig\u00eda para pedir la revocatoria del mandato del presidente Daniel Noboa y la vicepresidenta Mar\u00eda Jos\u00e9 Pinto. La decisi\u00f3n un\u00e1nime se da porque no encontraron pruebas suficientes que corroboren que el presidente incumpli\u00f3 su plan de Gobierno y la causa adem\u00e1s quedar\u00e1 archivada. Institucionesgubernamentales.<\/p>\n<p>Los consejeros se\u00f1alaron que el pedido habr\u00eda incumplido varios requisitos. Uno de ellos es que no se habr\u00eda podido demostrar que el mandatario haya incumplido con el plan de trabajo plurianual presentado.<\/p>\n<p>Seg\u00fan los consejeros, los peticionarios tampoco habr\u00edan podido demostrar que Daniel Noboa haya violado alguna disposici\u00f3n constitucional sobre las funciones, deberes y competencias asumidas desde el 14 de mayo de 2025, cuando se posesion\u00f3 como presidente de la Rep\u00fablica.<\/p>\n<p>El pedido de revocatoria estaba liderado por Leonidas Iza y el abogado corre\u00edsta Washington Andrade. (I)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todos los integrantes del Consejo Nacional Electoral (CNE) resolvierron con cinco votos negativos no dar paso a la entrega de formularios que el frente Revocatoria.ec exig\u00eda para pedir la revocatoria del mandato del presidente Daniel Noboa y la vicepresidenta Mar\u00eda Jos\u00e9 Pinto. La decisi\u00f3n un\u00e1nime se da porque no encontraron pruebas suficientes que corroboren que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23423,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"_links":{"self":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23422"}],"collection":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/comments?post=23422"}],"version-history":[{"count":1,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23422\/revisions"}],"predecessor-version":[{"id":23424,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23422\/revisions\/23424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media\/23423"}],"wp:attachment":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media?parent=23422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/categories?post=23422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/tags?post=23422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}