{"id":23370,"date":"2026-07-14T21:11:30","date_gmt":"2026-07-14T21:11:30","guid":{"rendered":"https:\/\/infozamoraec.com\/?p=23370"},"modified":"2026-07-14T21:11:30","modified_gmt":"2026-07-14T21:11:30","slug":"concejo-municipal-de-zamora-aprobo-convenios-y-ordenanza","status":"publish","type":"post","link":"https:\/\/infozamoraec.com\/index.php\/2026\/07\/14\/concejo-municipal-de-zamora-aprobo-convenios-y-ordenanza\/","title":{"rendered":"Concejo Municipal de Zamora aprob\u00f3 convenios y ordenanza"},"content":{"rendered":"<p>El Concejo Municipal de Zamora desarroll\u00f3 este martes 14 de julio de 2026 una sesi\u00f3n ordinaria presidida por la alcaldesa encargada, Blanca Carri\u00f3n, por delegaci\u00f3n del alcalde Manuel Gonz\u00e1lez. La reuni\u00f3n se efectu\u00f3 en el Sal\u00f3n del Pueblo con la participaci\u00f3n de los concejales Wilmer Espinoza, Ximena Monta\u00f1o, Ximena Meza y Franz Regalado.<\/p>\n<p>Durante la sesi\u00f3n, el cuerpo edilicio aprob\u00f3 por unanimidad la suscripci\u00f3n de un convenio de delegaci\u00f3n de competencias, sin transferencia de recursos, entre el GAD Municipal de Zamora y el GAD Parroquial Rural de Guadalupe para la reconstrucci\u00f3n del Centro Social Intercultural y Comunitario del barrio San Antonio del Vergel.<\/p>\n<p>Asimismo, se autoriz\u00f3 un segundo convenio de delegaci\u00f3n de competencias para la construcci\u00f3n de bater\u00edas sanitarias en el Centro Shuar Kantsam Alto, ubicado en la parroquia Guadalupe.<\/p>\n<p>En el \u00e1mbito normativo, el Concejo aprob\u00f3 en segundo y definitivo debate la ordenanza que regula el pago de la jubilaci\u00f3n patronal y la indemnizaci\u00f3n por acogerse a la jubilaci\u00f3n de los trabajadores del GAD Municipal de Zamora.<\/p>\n<p>Los ediles tambi\u00e9n conocieron la Resoluci\u00f3n Ejecutiva N.\u00b0 GADMZ-ACZ-0163-2026, relacionada con la Reforma del Traspaso de Cr\u00e9dito N.\u00b0 11, destinada a financiar diversas necesidades institucionales.<\/p>\n<p>Otro de los puntos aprobados fue la incorporaci\u00f3n del GAD Municipal de Sevilla Don Bosco al Consorcio de Municipios Amaz\u00f3nicos y Gal\u00e1pagos (COMAGA), autorizando al Ejecutivo Municipal la suscripci\u00f3n de la adenda correspondiente al convenio de mancomunidad, conforme a lo establecido en el COOTAD.<\/p>\n<p>Finalmente, el Concejo aprob\u00f3 el acta de la sesi\u00f3n ordinaria realizada el 30 de junio de 2026, dando cumplimiento al orden del d\u00eda previsto para la jornada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Concejo Municipal de Zamora desarroll\u00f3 este martes 14 de julio de 2026 una sesi\u00f3n ordinaria presidida por la alcaldesa encargada, Blanca Carri\u00f3n, por delegaci\u00f3n del alcalde Manuel Gonz\u00e1lez. La reuni\u00f3n se efectu\u00f3 en el Sal\u00f3n del Pueblo con la participaci\u00f3n de los concejales Wilmer Espinoza, Ximena Monta\u00f1o, Ximena Meza y Franz Regalado. Durante la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23371,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23370"}],"collection":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/comments?post=23370"}],"version-history":[{"count":1,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23370\/revisions"}],"predecessor-version":[{"id":23372,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/posts\/23370\/revisions\/23372"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media\/23371"}],"wp:attachment":[{"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/media?parent=23370"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/categories?post=23370"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infozamoraec.com\/index.php\/wp-json\/wp\/v2\/tags?post=23370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}